{"id":2530,"date":"2020-12-16T20:08:18","date_gmt":"2020-12-17T01:08:18","guid":{"rendered":"https:\/\/walkuproslindale.org\/weblog\/?p=2530"},"modified":"2020-12-18T12:28:10","modified_gmt":"2020-12-18T17:28:10","slug":"walkup-roslindale-snow-clearance-collaborative-version-4-1-virtually-socially-distanced-yours","status":"publish","type":"post","link":"https:\/\/walkuproslindale.org\/weblog\/2020\/12\/16\/walkup-roslindale-snow-clearance-collaborative-version-4-1-virtually-socially-distanced-yours\/","title":{"rendered":"EXAMPLE ADDED: WalkUP Roslindale Snow Clearance Collaborative &#8211; Version 4.1 (Virtually, Socially Distanced Yours)"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/media2.s-nbcnews.com\/j\/MSNBC\/Components\/Video\/150210\/tdy_or_yeti_150210.social_share_1024x512_center.jpg?w=648&#038;ssl=1\" alt=\"Boston Yeti' spotted shoveling snow has become an online sensation\" \/><\/p>\n<p>Friends, our good buddy Boston Yeti is telling us that we may have some significant snowfall overnight tonight and so, once the snow has stopped flying, we are calling out all of our WalkUP Roslindale Snow Clearance Collaborative Version 4.1 forces in a virtual, socially distanced way to don a face covering, pickup a shovel, and safely and calmly dig out a bus stop or two wherever in Roslindale they may be, then send us a picture of the dug out stop(s) at <a href=\"mailto:mlawlor@rc.com\">mlawlor@rc.com<\/a>, and we&#8217;ll be happy to give you kudos and, possibly, a reward if we can work out the details with a key provider of certain discount coupons for neighborhood businesses. Thanks!<\/p>\n<p>As an example, below are photos of the before and after for a bus stop access point that your correspondent shoveled out late yesterday at South &amp; Walter. Would love to post photos from others on their efforts! &#8211; mjl<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1524-scaled.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2536\" data-permalink=\"https:\/\/walkuproslindale.org\/weblog\/2020\/12\/16\/walkup-roslindale-snow-clearance-collaborative-version-4-1-virtually-socially-distanced-yours\/img_1524\/\" data-orig-file=\"https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1524-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 11&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1608223381&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.25&quot;,&quot;iso&quot;:&quot;640&quot;,&quot;shutter_speed&quot;:&quot;0.033333333333333&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_1524\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1524-scaled.jpg?fit=648%2C864&amp;ssl=1\" class=\"alignnone  wp-image-2536\" src=\"https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1524-scaled.jpg?resize=248%2C331&#038;ssl=1\" alt=\"\" width=\"248\" height=\"331\" srcset=\"https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1524-scaled.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1524-scaled.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1524-scaled.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1524-scaled.jpg?resize=1152%2C1536&amp;ssl=1 1152w, https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1524-scaled.jpg?resize=1536%2C2048&amp;ssl=1 1536w, https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1524-scaled.jpg?w=1296&amp;ssl=1 1296w\" sizes=\"auto, (max-width: 248px) 100vw, 248px\" \/><\/a> <a href=\"https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1525-scaled.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2537\" data-permalink=\"https:\/\/walkuproslindale.org\/weblog\/2020\/12\/16\/walkup-roslindale-snow-clearance-collaborative-version-4-1-virtually-socially-distanced-yours\/img_1525\/\" data-orig-file=\"https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1525-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 11&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1608223525&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.25&quot;,&quot;iso&quot;:&quot;1000&quot;,&quot;shutter_speed&quot;:&quot;0.033333333333333&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_1525\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1525-scaled.jpg?fit=648%2C864&amp;ssl=1\" class=\"alignnone  wp-image-2537\" src=\"https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1525-scaled.jpg?resize=248%2C331&#038;ssl=1\" alt=\"\" width=\"248\" height=\"331\" srcset=\"https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1525-scaled.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1525-scaled.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1525-scaled.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1525-scaled.jpg?resize=1152%2C1536&amp;ssl=1 1152w, https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1525-scaled.jpg?resize=1536%2C2048&amp;ssl=1 1536w, https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1525-scaled.jpg?w=1296&amp;ssl=1 1296w\" sizes=\"auto, (max-width: 248px) 100vw, 248px\" \/><\/a> <a href=\"https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1526-scaled.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2538\" data-permalink=\"https:\/\/walkuproslindale.org\/weblog\/2020\/12\/16\/walkup-roslindale-snow-clearance-collaborative-version-4-1-virtually-socially-distanced-yours\/img_1526\/\" data-orig-file=\"https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1526-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 11&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1608223863&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.25&quot;,&quot;iso&quot;:&quot;1000&quot;,&quot;shutter_speed&quot;:&quot;0.033333333333333&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_1526\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1526-scaled.jpg?fit=648%2C864&amp;ssl=1\" class=\"alignnone  wp-image-2538\" src=\"https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1526-scaled.jpg?resize=248%2C331&#038;ssl=1\" alt=\"\" width=\"248\" height=\"331\" srcset=\"https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1526-scaled.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1526-scaled.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1526-scaled.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1526-scaled.jpg?resize=1152%2C1536&amp;ssl=1 1152w, https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1526-scaled.jpg?resize=1536%2C2048&amp;ssl=1 1536w, https:\/\/i0.wp.com\/walkuproslindale.org\/weblog\/wp-content\/uploads\/2020\/12\/IMG_1526-scaled.jpg?w=1296&amp;ssl=1 1296w\" sizes=\"auto, (max-width: 248px) 100vw, 248px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Friends, our good buddy Boston Yeti is telling us that we may have some significant snowfall overnight tonight and so, once the snow has stopped flying, we are calling out all of our WalkUP Roslindale Snow Clearance Collaborative Version 4.1 forces in a virtual, socially distanced way to don a face covering, pickup a shovel, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[151,13],"tags":[422,454],"class_list":["post-2530","post","type-post","status-publish","format-standard","hentry","category-events","category-safety","tag-boston-yeti","tag-roslindale-snow-clearance-collaborative"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6X5no-EO","jetpack-related-posts":[],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/walkuproslindale.org\/weblog\/wp-json\/wp\/v2\/posts\/2530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/walkuproslindale.org\/weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/walkuproslindale.org\/weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/walkuproslindale.org\/weblog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/walkuproslindale.org\/weblog\/wp-json\/wp\/v2\/comments?post=2530"}],"version-history":[{"count":3,"href":"https:\/\/walkuproslindale.org\/weblog\/wp-json\/wp\/v2\/posts\/2530\/revisions"}],"predecessor-version":[{"id":2539,"href":"https:\/\/walkuproslindale.org\/weblog\/wp-json\/wp\/v2\/posts\/2530\/revisions\/2539"}],"wp:attachment":[{"href":"https:\/\/walkuproslindale.org\/weblog\/wp-json\/wp\/v2\/media?parent=2530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/walkuproslindale.org\/weblog\/wp-json\/wp\/v2\/categories?post=2530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/walkuproslindale.org\/weblog\/wp-json\/wp\/v2\/tags?post=2530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}